{"id":27318,"date":"2023-09-26T23:27:51","date_gmt":"2023-09-26T21:27:51","guid":{"rendered":"https:\/\/swiss-watch-passport.ch\/?p=27318"},"modified":"2023-09-26T23:50:35","modified_gmt":"2023-09-26T21:50:35","slug":"ssc-journee-detudes-expresso-avec-michele-fazzone","status":"publish","type":"post","link":"https:\/\/swiss-watch-passport.ch\/en\/ssc-journee-detudes-expresso-avec-michele-fazzone\/","title":{"rendered":"SSC Journ\u00e9e d&#8217;Etudes: expresso avec Michele Fazzone"},"content":{"rendered":"<section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><strong>Comme le veulent les statuts de cette v\u00e9n\u00e9rable soci\u00e9t\u00e9 fond\u00e9e en 1924 et dont le journal suisse d&#8217;horlogerie JSH fut l&#8217;organe officiel durant plusieurs d\u00e9cennies, la pr\u00e9sidence change chaque trois ans. Rencontre avec le pr\u00e9sident sortant.<\/strong><\/p>\n<p><i>Jo\u00ebl A.\u00a0Grandjean,\u00a0R\u00e9dacteur en chef JSH &amp; Swiss Watch Passport (by JSH)<\/i><br \/>\n<em><a href=\"https:\/\/www.instagram.com\/trpublicrelations\/\">Insta<\/a>\u00a0|\u00a0<a href=\"https:\/\/www.linkedin.com\/company\/trp-public-relations\/\">Linkedin<\/a>\u00a0|\u00a0<a href=\"https:\/\/www.facebook.com\/TheRightPlace.ch\/\">Facebook<\/a>\u00a0|\u00a0<a href=\"https:\/\/www.instagram.com\/jshmagazine1876\/\">Insta JSH<\/a>\u00a0|\u00a0<a href=\"https:\/\/www.instagram.com\/swisswatchpassport\/\">Insta SWP<\/a>\u00a0|\u00a0<a href=\"https:\/\/www.jsh-journal-suisse-horlogerie.org\/443209045\/category\/1341413\/abos-pubs\">S\u2019abonner \u00e0 JSH<\/a><\/em><\/p>\n<blockquote>\n<p style=\"text-align: right;\"><span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"http:\/\/bit.ly\/3TQGW6K\">Interview parue dans le<\/a> <a style=\"color: #0000ff;\" href=\"http:\/\/bit.ly\/3TQGW6K\">Hors-S\u00e9rie<\/a> <a style=\"color: #0000ff;\" href=\"http:\/\/bit.ly\/3TQGW6K\">du journal suisse d&#8217;horlogerie JSH enti\u00e8rement d\u00e9di\u00e9 \u00e0 la SSC<\/a><\/em><\/span><\/p>\n<\/blockquote>\n<\/div><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1320\" height=\"743\" src=\"https:\/\/swiss-watch-passport.ch\/wp-content\/uploads\/2023\/09\/01B_PHOTOS_JSH-MICHEL-FAZZONE-jaeger-lecoultre-scene-SSC-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/swiss-watch-passport.ch\/wp-content\/uploads\/2023\/09\/01B_PHOTOS_JSH-MICHEL-FAZZONE-jaeger-lecoultre-scene-SSC-scaled.jpg 1320w, https:\/\/swiss-watch-passport.ch\/wp-content\/uploads\/2023\/09\/01B_PHOTOS_JSH-MICHEL-FAZZONE-jaeger-lecoultre-scene-SSC-300x169.jpg 300w, https:\/\/swiss-watch-passport.ch\/wp-content\/uploads\/2023\/09\/01B_PHOTOS_JSH-MICHEL-FAZZONE-jaeger-lecoultre-scene-SSC-600x338.jpg 600w\" sizes=\"auto, (max-width: 1320px) 100vw, 1320px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Michel Fazzone annoncera le nom de son successeur lors de la Journ\u00e9e d&#8217;Etude annuelle, le jeudi 28 septembre 2023 au SwissTech Convention Center \u00e0 Ecublens. D&#8217;ici l\u00e0, portrait d&#8217;une personnalit\u00e9 dont le nom est li\u00e9 \u00e0 la grande Maison Jaeger-LeCoultre au Sentier.<\/p>\n<p>Il semblerait qu\u2019il y ait en ce moment dans la Manufacture au Sentier (Vall\u00e9e de Joux) des mouvements d\u2019envergure dans les archives: du tri, des d\u00e9placements de tr\u00e9sors, de la valorisation, de la sauvegarde patrimoniale en perspective&#8230;<\/p>\n<p><strong>\u00abL\u2019enfant de la Manufacture\u00bb<\/strong><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>S\u00fbr que Michele Fazzone est mis \u00e0 contribution lui qui, en marge de son engagement \u00abde milice\u00bb \u00e0 la Soci\u00e9t\u00e9 Suisse de Chronom\u00e9trie, est le directeur Manufacturing de la Grande Maison. Car depuis l\u2019\u00e2ge de 6 ans, il en arpente les m\u00e9andres et les recoins, puisque ses parents y travaillaient d\u00e9j\u00e0 et m\u00eame, apr\u00e8s leurs heures, embarquaient leur fils dans leurs t\u00e2ches de m\u00e9nage des locaux. \u00ab<em>Mes parents ont pass\u00e9 plus de 80 ans \u00e0 eux deux dans la grande maison. J\u2019y ai pris go\u00fbt, me voil\u00e0 dans ma 27\u00e8me ann\u00e9e!<\/em>\u00bb Certains \u2018vieux de la vieille\u2019, immuables figures combi\u00e8res crois\u00e9es lors de visites en ces terroirs horlogers, s\u2019en rappellent encore&#8230;<\/p>\n<p>A son tour, et le format l\u2019oblige, Monsieur le Pr\u00e9sident se pr\u00eate au jeu des questions cash de \u00ab<em>l\u2019Expresso avec&#8230;<\/em>\u00bb Interview v\u00e9rit\u00e9, qui ne prend pas de gants.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><strong>Pr\u00e9sident de la SSC? Sous votre sympathie naturelle sommeille un ambitieux, ou un pistonn\u00e9?<\/strong><\/p>\n<p>C\u2019est un bien grand titre! L\u2019important, c\u2019est ce qu\u2019on arrive \u00e0 faire tous ensemble. Et r\u00e9ussir \u00e0 le faire en s\u2019amusant, c\u2019est encore mieux! Je suis membre de la SSC depuis 25 ans. J\u2019ai toujours \u00e9t\u00e9 fascin\u00e9 par les rencontres qu\u2019on pouvait y faire. Un jour, je suis pass\u00e9 du c\u00f4t\u00e9 des conf\u00e9renciers et l\u00e0, les \u00e9motions sont encore diff\u00e9rentes. C\u2019est le Pr\u00e9sident de l\u2019ancien bureau qui est venu me proposer le d\u00e9fi. J\u2019avoue avoir tr\u00e8s peu h\u00e9sit\u00e9 d\u2019autant que j\u2019ai re\u00e7u le soutien de ma hi\u00e9rarchie. Je ne savais pas vraiment ce que cela allait repr\u00e9senter comme travail mais je me suis dit que c\u2019\u00e9tait le moment de rendre \u00e0 la SSC ce qu\u2019elle m\u2019avait donn\u00e9. Donc pas pistonn\u00e9, mais plut\u00f4t fortement soutenu&#8230;<\/p>\n<p><strong>Le r\u00e9seautage, \u00e7a compte! Comment sont les relations dans un monde en \u00abcircuit ferm\u00e9\u00bb comme la vall\u00e9e de Joux?<\/strong><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_none meta_simple\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1023\" height=\"1320\" src=\"https:\/\/swiss-watch-passport.ch\/wp-content\/uploads\/2023\/09\/01_JSH-SSC_Cover-dates-2023-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/swiss-watch-passport.ch\/wp-content\/uploads\/2023\/09\/01_JSH-SSC_Cover-dates-2023-scaled.jpg 1023w, https:\/\/swiss-watch-passport.ch\/wp-content\/uploads\/2023\/09\/01_JSH-SSC_Cover-dates-2023-233x300.jpg 233w, https:\/\/swiss-watch-passport.ch\/wp-content\/uploads\/2023\/09\/01_JSH-SSC_Cover-dates-2023-465x600.jpg 465w\" sizes=\"auto, (max-width: 1023px) 100vw, 1023px\" \/><\/div><div class=\"w-image-meta\"><div class=\"w-image-title\">La couverture du hors-s\u00e9rie SSC du journal suisse d'horlogerie annon\u00e7ant la journ\u00e9e d'Etudes du 28 septembre 2023 intitul\u00e9e \"La Transmission Dans Tous Ses Etats\"<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Nous avons ici une chance \u00e9norme \u00e0 la Vall\u00e9e de Joux, celle de vouloir se d\u00e9passer tous ensemble pour un objectif commun. Nous avons beaucoup de projets qui impliquent tous les acteurs de la Vall\u00e9e de Joux, que ce soit via la <a href=\"https:\/\/davel.vd.ch\/partnerdetail.aspx?ID=824\">SIC<\/a>, l\u2019<a href=\"http:\/\/www.adaev.ch\">ADAEV<\/a> ou alors l\u2019<a href=\"https:\/\/www.etvj.ch\">\u00c9cole Technique de la Vall\u00e9e de Joux<\/a>. Ces projets nous permettent de faire union et, dans ce cadre, nous mettons nos savoirs \u00e0 disposition dans nos diff\u00e9rentes maisons. Nous avons donc des relations formelles et informelles, mais dans le respect de la confidentialit\u00e9 de chacun.<\/p>\n<p>Vous estimez-vous \u00abqualifi\u00e9\u00bb pour g\u00e9rer un bateau tel que la SSC? Qu\u2019attend-on d\u2019un Pr\u00e9sident?<\/p>\n<p>Je fais de mon mieux. Et j\u2019ai autour de moi une \u00e9quipe incroyable et il parait, aussi folle que moi; peut-on en d\u00e9duire que nous sommes qualifi\u00e9s? Nous avons essay\u00e9 d\u2019apporter une dynamique \u00e0 la SSC tout en perp\u00e9tuant l\u2019excellent travail des pr\u00e9c\u00e9dents bureaux. Le r\u00f4le du pr\u00e9sident est double pendant ces 3 ans, pr\u00e9sider le bureau et la SSC en m\u00eame temps. C\u2019est une complexit\u00e9 et une charge importante mais cela me permet d\u2019apporter de nouvelles id\u00e9es tout en assurant l\u2019ADN de la SSC.<\/p>\n<p><strong>\u00c9videmment, vous arguez que vous n\u2019\u00eates pas seul, que vous ne seriez rien sans votre \u00e9quipe! Parlez-nous donc de ce Comit\u00e9?<\/strong><\/p>\n<p>J\u2019ai constitu\u00e9 mon bureau avec deux sp\u00e9cificit\u00e9s qui me tenaient \u00e0 c\u0153ur. M\u2019entourer d\u2019abord de personnes n\u2019ayant jamais \u00e9t\u00e9 acteurs auparavant dans la SSC. Ce afin d\u2019avoir des membres innovants tout en ayant un esprit horloger. Puis, comme la plupart ne se connaissait pas, il y a eu un \u00ab<em>m\u00e9lange de cultures.<\/em>\u00bb En effet, dans l\u2019\u00e9quipe j\u2019ai des coll\u00e8gues de travail, des repr\u00e9sentants de marques concurrentes, des fournisseurs partenaires ainsi que l\u2019ETVJ (<a href=\"https:\/\/www.etvj.ch\">\u00c9cole Technique de la Vall\u00e9e de Joux<\/a>).<\/p>\n<blockquote>\n<p><em>D\u00e8s notre premi\u00e8re r\u00e9union, le feeling \u00e9tait au rendez-vous et l\u2019\u00e9quipe pr\u00eate \u00e0 relever les challenges les plus fous. Une aventure incroyable et d\u00e9sormais, une belle \u00e9quipe d\u2019amis.<\/em><\/p>\n<\/blockquote>\n<p><strong>Au fait, rappelez-nous comment se passent les \u00e9lections des pr\u00e9sidents et de leur bureau?<\/strong><\/p>\n<p>C\u2019est le pr\u00e9sident sortant qui propose son rempla\u00e7ant en respectant le tournus des r\u00e9gions. Ensuite, le nouveau pr\u00e9sident constitue son \u00e9quipe et la propose au comit\u00e9 et \u00e0 l\u2019Assembl\u00e9e G\u00e9n\u00e9rale qui doivent l\u2019\u00e9lire tous les deux.<\/p>\n<p><strong>Quels sont les \u00abComit\u00e9s\u00bb et leur utilit\u00e9?<\/strong><\/p>\n<p>Aujourd\u2019hui la SSC est g\u00e9r\u00e9e par un comit\u00e9 constitu\u00e9 de quatre r\u00e9gions et de plusieurs partenaires importants de l\u2019horlogerie. Il y a ensuite un bureau qui repr\u00e9sente une r\u00e9gion et qui g\u00e8re pendant trois ans les diff\u00e9rents \u00e9v\u00e9nements en parfaite autonomie tout en continuant le d\u00e9veloppement de la SSC. Il y a deux commissions importantes, \u00ab<em>Le concours de r\u00e9glage<\/em>\u00bb et \u00abla <em>Commission du Bulletin<\/em> (<em>ndlr: la publication bisannuelle de la SSC<\/em>)\u00bb. Nous pouvons nous appuyer sur un secr\u00e9tariat central, <a href=\"https:\/\/www.centredoc.swiss\/en\/\">Centredoc<\/a>. Ce-dernier nous soutient op\u00e9rationnellement et surtout son repr\u00e9sentant fait partie du bureau. La particularit\u00e9 est que le pr\u00e9sident du bureau est \u00e9galement le pr\u00e9sident de la SSC pendant son mandat.<\/p>\n<\/div><\/div><div class=\"w-image align_none meta_simple\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1320\" height=\"880\" src=\"https:\/\/swiss-watch-passport.ch\/wp-content\/uploads\/2023\/09\/JSH-SWISS-WATCH-PASSPORT-MICHEL-FAZZONE-ET-BUREAU_SSC-OK-106-copie-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/swiss-watch-passport.ch\/wp-content\/uploads\/2023\/09\/JSH-SWISS-WATCH-PASSPORT-MICHEL-FAZZONE-ET-BUREAU_SSC-OK-106-copie-scaled.jpg 1320w, https:\/\/swiss-watch-passport.ch\/wp-content\/uploads\/2023\/09\/JSH-SWISS-WATCH-PASSPORT-MICHEL-FAZZONE-ET-BUREAU_SSC-OK-106-copie-300x200.jpg 300w, https:\/\/swiss-watch-passport.ch\/wp-content\/uploads\/2023\/09\/JSH-SWISS-WATCH-PASSPORT-MICHEL-FAZZONE-ET-BUREAU_SSC-OK-106-copie-600x400.jpg 600w\" sizes=\"auto, (max-width: 1320px) 100vw, 1320px\" \/><\/div><div class=\"w-image-meta\"><div class=\"w-image-title\">Michele Fazzone (tt \u00e0 g), pr\u00e9sident de la SSC, et son Bureau (2021-2023), sur la sc\u00e8ne du SwissTech Convention Center (EPFL).<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><strong>Les \u00ab<em>appels \u00e0 conf\u00e9renciers<\/em>\u00bb surgissent r\u00e9guli\u00e8rement dans l\u2019actualit\u00e9 horlog\u00e8re. Qui se pr\u00e9sente, quelles sont les conditions pour postuler?<\/strong><\/p>\n<p>L\u2019appel est ouvert \u00e0 tous, nous \u00e9tudions toutes les propositions. Nous disposons d\u2019une commission scientifique au sein du bureau. Elle r\u00e9alise un \u00e9norme boulot en essayant de construire un programme \u00e9quilibr\u00e9 par rapport aux choix de th\u00e9matiques. Devoir dire non \u00e0 une conf\u00e9rence est toujours p\u00e9nible. Mais nous avons aussi le \u00ab<a href=\"https:\/\/www.ssc.ch\/manifestations-details\/article\/petit-dejeuner-horloger-2023\/\"><em>Petit-D\u00e9jeuner Horloger<\/em><\/a>\u00bb qui ouvre des possibilit\u00e9s et donne de la place \u00e9galement pour des conf\u00e9rences. Trouver des conf\u00e9rences de qualit\u00e9 est primordial. Mais le travail pr\u00e9paratoire entre les conf\u00e9renciers et la commission scientifique est un gage de r\u00e9ussite pour le jour J.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-btn-wrapper align_none\"><a class=\"w-btn us-btn-style_1\" href=\"https:\/\/bit.ly\/3TQGW6K\"><span class=\"w-btn-label\">JSH Hors-S\u00e9rie SSC<\/span><\/a><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-btn-wrapper align_none\"><a class=\"w-btn us-btn-style_1\" href=\"https:\/\/www.ssc.ch\"><span class=\"w-btn-label\">SSC, Since 1924 (officiel)<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-html\"><div style=\"position:relative;padding-top:max(60%,326px);height:0;width:100%\"><iframe allow=\"clipboard-write\" sandbox=\"allow-top-navigation allow-top-navigation-by-user-activation allow-downloads allow-scripts allow-same-origin allow-popups allow-modals allow-popups-to-escape-sandbox allow-forms\" allowfullscreen=\"true\" style=\"position:absolute;border:none;width:100%;height:100%;left:0;right:0;top:0;bottom:0;\" src=\"https:\/\/e.issuu.com\/embed.html?d=jsh-hors-serie-ssc-2022_soumission-ssc&u=tagpress41\"><\/iframe><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Comme le veulent les statuts de cette v\u00e9n\u00e9rable soci\u00e9t\u00e9 fond\u00e9e en 1924 et dont le journal suisse d&#8217;horlogerie JSH fut l&#8217;organe officiel durant plusieurs d\u00e9cennies, la pr\u00e9sidence change chaque trois ans. Rencontre avec le pr\u00e9sident sortant. Jo\u00ebl A.\u00a0Grandjean,\u00a0R\u00e9dacteur en chef JSH &amp; Swiss Watch Passport (by JSH) Insta\u00a0|\u00a0Linkedin\u00a0|\u00a0Facebook\u00a0|\u00a0Insta JSH\u00a0|\u00a0Insta SWP\u00a0|\u00a0S\u2019abonner \u00e0 JSH Interview parue dans...","protected":false},"author":2,"featured_media":27322,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3565,4133,3601,3599,3566,6007],"tags":[6419,4949,3638,3640,5992,6420,3642,3644,3645,3646,3776,3649,3650,3651,4953,3653,3654,3655,3657,3658,3659],"class_list":["post-27318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1010-10h10-10past10","category-1st-en","category-jsh-print","category-view","category-suppliers","category-whoareu","tag-1924-en","tag-chronometrie-en","tag-cotraitants-en","tag-editorinchief-en","tag-ephj2024-en","tag-fazzone-en","tag-fournisseurs-en","tag-horlogerie-en","tag-journalsuissehorlogerie-en","tag-jsh1876-en","tag-patek-en","tag-ppdc-en","tag-prowatch-en","tag-rolex-en","tag-ssc-en","tag-swisswatchpassport-en","tag-tagpress41-en","tag-therightplace2be-en","tag-watchcafe-en","tag-watchmaking-en","tag-watchpassport-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SSC Journ\u00e9e d&#039;Etudes: expresso avec Michele Fazzone - Watch Passports by JSH\u00ae<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swiss-watch-passport.ch\/en\/ssc-journee-detudes-expresso-avec-michele-fazzone\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SSC Journ\u00e9e d&#039;Etudes: expresso avec Michele Fazzone - Watch Passports by JSH\u00ae\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swiss-watch-passport.ch\/en\/ssc-journee-detudes-expresso-avec-michele-fazzone\/\" \/>\n<meta property=\"og:site_name\" content=\"Watch Passports by JSH\u00ae\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/joel.grandjean\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-26T21:27:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-26T21:50:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swiss-watch-passport.ch\/wp-content\/uploads\/2023\/09\/00_JSH-swiss-watch-passport-MICHEL-FAZZONE-jaeger-lecoultre-12_-copie-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1320\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u270d Joel A. Grandjean\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/tagpress\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u270d Joel A. Grandjean\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/ssc-journee-detudes-expresso-avec-michele-fazzone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/ssc-journee-detudes-expresso-avec-michele-fazzone\\\/\"},\"author\":{\"name\":\"\u270d Joel A. Grandjean\",\"@id\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/#\\\/schema\\\/person\\\/f94b16e809fd2ec84af9c81937bf549b\"},\"headline\":\"SSC Journ\u00e9e d&#8217;Etudes: expresso avec Michele Fazzone\",\"datePublished\":\"2023-09-26T21:27:51+00:00\",\"dateModified\":\"2023-09-26T21:50:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/ssc-journee-detudes-expresso-avec-michele-fazzone\\\/\"},\"wordCount\":1487,\"image\":{\"@id\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/ssc-journee-detudes-expresso-avec-michele-fazzone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/00_JSH-swiss-watch-passport-MICHEL-FAZZONE-jaeger-lecoultre-12_-copie-1-scaled.jpg\",\"keywords\":[\"1924\",\"Chronom\u00e9trie\",\"cotraitants\",\"EditorInChief\",\"EPHJ2024\",\"Fazzone\",\"Fournisseurs\",\"Horlogerie\",\"JournalSuisseHorlogerie\",\"jsh1876\",\"Patek\",\"PPDC\",\"Prowatch\",\"Rolex\",\"SSC\",\"SwissWatchPassport\",\"tagpress41\",\"therightplace2be\",\"WatCHCafe\",\"Watchmaking\",\"WatchPassport\"],\"articleSection\":[\"10:10\",\"1st\",\"JSH\u00ae PRINT\",\"OPINION\",\"SUPPLIERS\",\"WhoAreU\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/ssc-journee-detudes-expresso-avec-michele-fazzone\\\/\",\"url\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/ssc-journee-detudes-expresso-avec-michele-fazzone\\\/\",\"name\":\"SSC Journ\u00e9e d'Etudes: expresso avec Michele Fazzone - Watch Passports by JSH\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/ssc-journee-detudes-expresso-avec-michele-fazzone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/ssc-journee-detudes-expresso-avec-michele-fazzone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/00_JSH-swiss-watch-passport-MICHEL-FAZZONE-jaeger-lecoultre-12_-copie-1-scaled.jpg\",\"datePublished\":\"2023-09-26T21:27:51+00:00\",\"dateModified\":\"2023-09-26T21:50:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/#\\\/schema\\\/person\\\/f94b16e809fd2ec84af9c81937bf549b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/ssc-journee-detudes-expresso-avec-michele-fazzone\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/ssc-journee-detudes-expresso-avec-michele-fazzone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/ssc-journee-detudes-expresso-avec-michele-fazzone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/00_JSH-swiss-watch-passport-MICHEL-FAZZONE-jaeger-lecoultre-12_-copie-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/00_JSH-swiss-watch-passport-MICHEL-FAZZONE-jaeger-lecoultre-12_-copie-1-scaled.jpg\",\"width\":1320,\"height\":850},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/ssc-journee-detudes-expresso-avec-michele-fazzone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SSC Journ\u00e9e d&rsquo;Etudes: expresso avec Michele Fazzone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/\",\"name\":\"Watch Passports by JSH\u00ae\",\"description\":\"JSH\u00ae spirit, L&#039;esprit du Journal Suisse d&#039;Horlogerie, le plus ancien m\u00e9dia horloger fond\u00e9 en 1876\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/#\\\/schema\\\/person\\\/f94b16e809fd2ec84af9c81937bf549b\",\"name\":\"\u270d Joel A. Grandjean\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ef4a158da8673a24dc02c72afb2fd8d98ab544725d60023ed25351e2f197e012?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ef4a158da8673a24dc02c72afb2fd8d98ab544725d60023ed25351e2f197e012?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ef4a158da8673a24dc02c72afb2fd8d98ab544725d60023ed25351e2f197e012?s=96&d=mm&r=g\",\"caption\":\"\u270d Joel A. Grandjean\"},\"description\":\"Chief editor &amp; publisher of the international watch magazine \\\"Swiss Watch Passport\u00ae (by JSH\u00ae)\\\" and of the Journal Suisse d'Horlogerie JSH\u00ae (the oldest Swiss Watch Journal founded in 1876). Member of Impressum, PressTourim and Club Suisse de la Presse, this Ivory Coast-born Swiss, descendant of a family of watchmakers, co-founded the magazines Montres Passion &amp; Uhren Welt at Ringier in 1993 with Kenan Tegin, as well as the Prix Montre de l'Ann\u00e9e. Founded in 2005, his press agency 1876 News (formerly T\u00e0G Press +41T) contributes to some twenty media through a network of around ten journalists or experts. These include Journal Suisse d'Horlogerie (2008-2014), Heure Suisse\\\/Schweiz and Ann\u00e9e Horlog\u00e8re, F\\\/D\\\/E (2011-2014), Watchonista.com (2013-2019). In 2019, he founded and chaired \\\"JSH Archives &amp; Patrimoine\\\" to relaunch the Swiss watchmaking journal JSH. Then in 2021, he built on his very first editorial venture, the \\\"bloghorloger.ch\\\" established on the web in 2003, to come back online with the Swiss Watch Passport\u00ae (by JSH\u00ae). Jo\u00ebl A. Grandjean is a member of the SSC, the Swiss Society of Chronometry, and of the jury of the Prix Ga\u00efa, aka the \\\"Nobel of watchmaking\\\" awarded since 1992 by the MIH, Le Mus\u00e9e International de l'Horlogerie in La Chaux-de-Fonds\",\"sameAs\":[\"https:\\\/\\\/grandjean.watch\",\"https:\\\/\\\/www.facebook.com\\\/joel.grandjean\",\"https:\\\/\\\/www.instagram.com\\\/grandjean.grammson\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/joel-a-grandjean-\u270d-5524357\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/x.com\\\/tagpress\",\"https:\\\/\\\/www.youtube.com\\\/@joela.grandjeanprowatchpre906\"],\"url\":\"https:\\\/\\\/swiss-watch-passport.ch\\\/en\\\/author\\\/joel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SSC Journ\u00e9e d'Etudes: expresso avec Michele Fazzone - Watch Passports by JSH\u00ae","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swiss-watch-passport.ch\/en\/ssc-journee-detudes-expresso-avec-michele-fazzone\/","og_locale":"en_US","og_type":"article","og_title":"SSC Journ\u00e9e d'Etudes: expresso avec Michele Fazzone - Watch Passports by JSH\u00ae","og_url":"https:\/\/swiss-watch-passport.ch\/en\/ssc-journee-detudes-expresso-avec-michele-fazzone\/","og_site_name":"Watch Passports by JSH\u00ae","article_author":"https:\/\/www.facebook.com\/joel.grandjean","article_published_time":"2023-09-26T21:27:51+00:00","article_modified_time":"2023-09-26T21:50:35+00:00","og_image":[{"width":1320,"height":850,"url":"https:\/\/swiss-watch-passport.ch\/wp-content\/uploads\/2023\/09\/00_JSH-swiss-watch-passport-MICHEL-FAZZONE-jaeger-lecoultre-12_-copie-1-scaled.jpg","type":"image\/jpeg"}],"author":"\u270d Joel A. Grandjean","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/x.com\/tagpress","twitter_misc":{"Written by":"\u270d Joel A. Grandjean","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/swiss-watch-passport.ch\/en\/ssc-journee-detudes-expresso-avec-michele-fazzone\/#article","isPartOf":{"@id":"https:\/\/swiss-watch-passport.ch\/en\/ssc-journee-detudes-expresso-avec-michele-fazzone\/"},"author":{"name":"\u270d Joel A. Grandjean","@id":"https:\/\/swiss-watch-passport.ch\/en\/#\/schema\/person\/f94b16e809fd2ec84af9c81937bf549b"},"headline":"SSC Journ\u00e9e d&#8217;Etudes: expresso avec Michele Fazzone","datePublished":"2023-09-26T21:27:51+00:00","dateModified":"2023-09-26T21:50:35+00:00","mainEntityOfPage":{"@id":"https:\/\/swiss-watch-passport.ch\/en\/ssc-journee-detudes-expresso-avec-michele-fazzone\/"},"wordCount":1487,"image":{"@id":"https:\/\/swiss-watch-passport.ch\/en\/ssc-journee-detudes-expresso-avec-michele-fazzone\/#primaryimage"},"thumbnailUrl":"https:\/\/swiss-watch-passport.ch\/wp-content\/uploads\/2023\/09\/00_JSH-swiss-watch-passport-MICHEL-FAZZONE-jaeger-lecoultre-12_-copie-1-scaled.jpg","keywords":["1924","Chronom\u00e9trie","cotraitants","EditorInChief","EPHJ2024","Fazzone","Fournisseurs","Horlogerie","JournalSuisseHorlogerie","jsh1876","Patek","PPDC","Prowatch","Rolex","SSC","SwissWatchPassport","tagpress41","therightplace2be","WatCHCafe","Watchmaking","WatchPassport"],"articleSection":["10:10","1st","JSH\u00ae PRINT","OPINION","SUPPLIERS","WhoAreU"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/swiss-watch-passport.ch\/en\/ssc-journee-detudes-expresso-avec-michele-fazzone\/","url":"https:\/\/swiss-watch-passport.ch\/en\/ssc-journee-detudes-expresso-avec-michele-fazzone\/","name":"SSC Journ\u00e9e d'Etudes: expresso avec Michele Fazzone - Watch Passports by JSH\u00ae","isPartOf":{"@id":"https:\/\/swiss-watch-passport.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swiss-watch-passport.ch\/en\/ssc-journee-detudes-expresso-avec-michele-fazzone\/#primaryimage"},"image":{"@id":"https:\/\/swiss-watch-passport.ch\/en\/ssc-journee-detudes-expresso-avec-michele-fazzone\/#primaryimage"},"thumbnailUrl":"https:\/\/swiss-watch-passport.ch\/wp-content\/uploads\/2023\/09\/00_JSH-swiss-watch-passport-MICHEL-FAZZONE-jaeger-lecoultre-12_-copie-1-scaled.jpg","datePublished":"2023-09-26T21:27:51+00:00","dateModified":"2023-09-26T21:50:35+00:00","author":{"@id":"https:\/\/swiss-watch-passport.ch\/en\/#\/schema\/person\/f94b16e809fd2ec84af9c81937bf549b"},"breadcrumb":{"@id":"https:\/\/swiss-watch-passport.ch\/en\/ssc-journee-detudes-expresso-avec-michele-fazzone\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swiss-watch-passport.ch\/en\/ssc-journee-detudes-expresso-avec-michele-fazzone\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/swiss-watch-passport.ch\/en\/ssc-journee-detudes-expresso-avec-michele-fazzone\/#primaryimage","url":"https:\/\/swiss-watch-passport.ch\/wp-content\/uploads\/2023\/09\/00_JSH-swiss-watch-passport-MICHEL-FAZZONE-jaeger-lecoultre-12_-copie-1-scaled.jpg","contentUrl":"https:\/\/swiss-watch-passport.ch\/wp-content\/uploads\/2023\/09\/00_JSH-swiss-watch-passport-MICHEL-FAZZONE-jaeger-lecoultre-12_-copie-1-scaled.jpg","width":1320,"height":850},{"@type":"BreadcrumbList","@id":"https:\/\/swiss-watch-passport.ch\/en\/ssc-journee-detudes-expresso-avec-michele-fazzone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/swiss-watch-passport.ch\/en\/"},{"@type":"ListItem","position":2,"name":"SSC Journ\u00e9e d&rsquo;Etudes: expresso avec Michele Fazzone"}]},{"@type":"WebSite","@id":"https:\/\/swiss-watch-passport.ch\/en\/#website","url":"https:\/\/swiss-watch-passport.ch\/en\/","name":"Watch Passports by JSH\u00ae","description":"JSH\u00ae spirit, L&#039;esprit du Journal Suisse d&#039;Horlogerie, le plus ancien m\u00e9dia horloger fond\u00e9 en 1876","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swiss-watch-passport.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/swiss-watch-passport.ch\/en\/#\/schema\/person\/f94b16e809fd2ec84af9c81937bf549b","name":"\u270d Joel A. Grandjean","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ef4a158da8673a24dc02c72afb2fd8d98ab544725d60023ed25351e2f197e012?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ef4a158da8673a24dc02c72afb2fd8d98ab544725d60023ed25351e2f197e012?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ef4a158da8673a24dc02c72afb2fd8d98ab544725d60023ed25351e2f197e012?s=96&d=mm&r=g","caption":"\u270d Joel A. Grandjean"},"description":"Chief editor &amp; publisher of the international watch magazine \"Swiss Watch Passport\u00ae (by JSH\u00ae)\" and of the Journal Suisse d'Horlogerie JSH\u00ae (the oldest Swiss Watch Journal founded in 1876). Member of Impressum, PressTourim and Club Suisse de la Presse, this Ivory Coast-born Swiss, descendant of a family of watchmakers, co-founded the magazines Montres Passion &amp; Uhren Welt at Ringier in 1993 with Kenan Tegin, as well as the Prix Montre de l'Ann\u00e9e. Founded in 2005, his press agency 1876 News (formerly T\u00e0G Press +41T) contributes to some twenty media through a network of around ten journalists or experts. These include Journal Suisse d'Horlogerie (2008-2014), Heure Suisse\/Schweiz and Ann\u00e9e Horlog\u00e8re, F\/D\/E (2011-2014), Watchonista.com (2013-2019). In 2019, he founded and chaired \"JSH Archives &amp; Patrimoine\" to relaunch the Swiss watchmaking journal JSH. Then in 2021, he built on his very first editorial venture, the \"bloghorloger.ch\" established on the web in 2003, to come back online with the Swiss Watch Passport\u00ae (by JSH\u00ae). Jo\u00ebl A. Grandjean is a member of the SSC, the Swiss Society of Chronometry, and of the jury of the Prix Ga\u00efa, aka the \"Nobel of watchmaking\" awarded since 1992 by the MIH, Le Mus\u00e9e International de l'Horlogerie in La Chaux-de-Fonds","sameAs":["https:\/\/grandjean.watch","https:\/\/www.facebook.com\/joel.grandjean","https:\/\/www.instagram.com\/grandjean.grammson\/","https:\/\/www.linkedin.com\/in\/joel-a-grandjean-\u270d-5524357\/","https:\/\/x.com\/https:\/\/x.com\/tagpress","https:\/\/www.youtube.com\/@joela.grandjeanprowatchpre906"],"url":"https:\/\/swiss-watch-passport.ch\/en\/author\/joel\/"}]}},"_links":{"self":[{"href":"https:\/\/swiss-watch-passport.ch\/en\/wp-json\/wp\/v2\/posts\/27318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swiss-watch-passport.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swiss-watch-passport.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swiss-watch-passport.ch\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/swiss-watch-passport.ch\/en\/wp-json\/wp\/v2\/comments?post=27318"}],"version-history":[{"count":0,"href":"https:\/\/swiss-watch-passport.ch\/en\/wp-json\/wp\/v2\/posts\/27318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swiss-watch-passport.ch\/en\/wp-json\/wp\/v2\/media\/27322"}],"wp:attachment":[{"href":"https:\/\/swiss-watch-passport.ch\/en\/wp-json\/wp\/v2\/media?parent=27318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swiss-watch-passport.ch\/en\/wp-json\/wp\/v2\/categories?post=27318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swiss-watch-passport.ch\/en\/wp-json\/wp\/v2\/tags?post=27318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}